{"id":2641,"date":"2021-07-31T06:19:39","date_gmt":"2021-07-31T06:19:39","guid":{"rendered":"http:\/\/localhost:8888\/wesecure\/?page_id=8"},"modified":"2025-11-06T15:49:14","modified_gmt":"2025-11-06T14:49:14","slug":"entreprise-alarme-saint-tropez","status":"publish","type":"page","link":"https:\/\/www.glssecurity.fr\/en\/","title":{"rendered":"Alarme vid\u00e9osurveillance golfe de Saint-Tropez"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"2641\" class=\"elementor elementor-2641\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1d67a64 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1d67a64\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ef31271\" data-id=\"ef31271\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-ep-wrapper-link=\"{&quot;url&quot;:&quot;#contact&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;,&quot;custom_attributes&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"bdt-element-link elementor-element elementor-element-c3fda25 elementor-align-left elementor-hidden-mobile bdt-navigation-type-arrows elementor-widget elementor-widget-bdt-slider\" data-id=\"c3fda25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bdt-slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div id=\"bdt-slider-c3fda25\" class=\"bdt-slider bdt-arrows-align-center\" data-settings=\"{&quot;autoplay&quot;:{&quot;delay&quot;:5000},&quot;loop&quot;:true,&quot;speed&quot;:500,&quot;pauseOnHover&quot;:true,&quot;effect&quot;:&quot;slide&quot;,&quot;fadeEffect&quot;:{&quot;crossFade&quot;:true},&quot;navigation&quot;:{&quot;nextEl&quot;:&quot;#bdt-slider-c3fda25 .bdt-navigation-next&quot;,&quot;prevEl&quot;:&quot;#bdt-slider-c3fda25 .bdt-navigation-prev&quot;},&quot;pagination&quot;:{&quot;el&quot;:&quot;#bdt-slider-c3fda25 .swiper-pagination&quot;,&quot;type&quot;:&quot;&quot;,&quot;clickable&quot;:&quot;true&quot;,&quot;dynamicBullets&quot;:false},&quot;scrollbar&quot;:{&quot;el&quot;:&quot;#bdt-slider-c3fda25 .swiper-scrollbar&quot;,&quot;hide&quot;:&quot;true&quot;}}\">\n\t\t\t<div class=\"swiper-carousel swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slider\" dir=\"ltr\">\n\t\t\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t<div class=\"bdt-slide-item swiper-slide bdt-slide-effect-left\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-slider-image-wrapper\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1598\" height=\"962\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/villa-saint-tropez-overlay-noir-1.png\" class=\"bdt-cover\" alt=\"Villa\" data-bdt-cover=\"1\" srcset=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/villa-saint-tropez-overlay-noir-1.png 1598w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/villa-saint-tropez-overlay-noir-1-300x181.png 300w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/villa-saint-tropez-overlay-noir-1-1024x616.png 1024w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/villa-saint-tropez-overlay-noir-1-768x462.png 768w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/villa-saint-tropez-overlay-noir-1-1536x925.png 1536w\" sizes=\"(max-width: 1598px) 100vw, 1598px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-slide-desc bdt-position-large bdt-position-center bdt-position-z-index\">\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-slide-text\">\n\t\t\t\t\t\t\t\t<p><img decoding=\"async\" class=\"alignnone wp-image-2808\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/LOGO-GROUPE-LAVAGNA-SECURITE-FONDS-TRANSPARENT-ECRITURES-BLANCHES-1-300x211.png\" alt=\"\" width=\"400\" height=\"281\" srcset=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/LOGO-GROUPE-LAVAGNA-SECURITE-FONDS-TRANSPARENT-ECRITURES-BLANCHES-1-300x211.png 300w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/LOGO-GROUPE-LAVAGNA-SECURITE-FONDS-TRANSPARENT-ECRITURES-BLANCHES-1-1024x719.png 1024w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/LOGO-GROUPE-LAVAGNA-SECURITE-FONDS-TRANSPARENT-ECRITURES-BLANCHES-1-768x539.png 768w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/LOGO-GROUPE-LAVAGNA-SECURITE-FONDS-TRANSPARENT-ECRITURES-BLANCHES-1-1536x1078.png 1536w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/LOGO-GROUPE-LAVAGNA-SECURITE-FONDS-TRANSPARENT-ECRITURES-BLANCHES-1.png 1549w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/p><p style=\"padding-right: 95px;\">Depuis 2010, nous concevons des solutions de s\u00e9curit\u00e9 sur mesure dans le Golfe de Saint-Tropez, en alliant expertise locale et technologies de pointe pour vous offrir une protection toujours \u00e0 la hauteur de vos attentes.<\/p>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-slide-link-wrapper\">\n\t\t\t\t\t\t\t\t<a class=\"bdt-slide-link\" href=\"#\">\n\n\t\t\t\t\t\t\t\t\tCONTACT US\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"bdt-slide-item swiper-slide bdt-slide-effect-left\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-slider-image-wrapper\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1597\" height=\"965\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/corporpiete-saint-tropez-overlay-noir.png\" class=\"bdt-cover\" alt=\"Copropri\u00e9t\u00e9\" data-bdt-cover=\"1\" srcset=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/corporpiete-saint-tropez-overlay-noir.png 1597w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/corporpiete-saint-tropez-overlay-noir-300x181.png 300w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/corporpiete-saint-tropez-overlay-noir-1024x619.png 1024w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/corporpiete-saint-tropez-overlay-noir-768x464.png 768w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/corporpiete-saint-tropez-overlay-noir-1536x928.png 1536w\" sizes=\"(max-width: 1597px) 100vw, 1597px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-slide-desc bdt-position-large bdt-position-center bdt-position-z-index\">\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-slide-text\">\n\t\t\t\t\t\t\t\t<p><img decoding=\"async\" class=\"alignnone wp-image-2808\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/LOGO-GROUPE-LAVAGNA-SECURITE-FONDS-TRANSPARENT-ECRITURES-BLANCHES-1-300x211.png\" alt=\"\" width=\"400\" height=\"281\" srcset=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/LOGO-GROUPE-LAVAGNA-SECURITE-FONDS-TRANSPARENT-ECRITURES-BLANCHES-1-300x211.png 300w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/LOGO-GROUPE-LAVAGNA-SECURITE-FONDS-TRANSPARENT-ECRITURES-BLANCHES-1-1024x719.png 1024w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/LOGO-GROUPE-LAVAGNA-SECURITE-FONDS-TRANSPARENT-ECRITURES-BLANCHES-1-768x539.png 768w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/LOGO-GROUPE-LAVAGNA-SECURITE-FONDS-TRANSPARENT-ECRITURES-BLANCHES-1-1536x1078.png 1536w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/LOGO-GROUPE-LAVAGNA-SECURITE-FONDS-TRANSPARENT-ECRITURES-BLANCHES-1.png 1549w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/p><p style=\"padding-right: 95px;\">Depuis 2010, nous concevons des solutions de s\u00e9curit\u00e9 sur mesure dans le Golfe de Saint-Tropez, en alliant expertise locale et technologies de pointe pour vous offrir une protection toujours \u00e0 la hauteur de vos attentes.<\/p>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-slide-link-wrapper\">\n\t\t\t\t\t\t\t\t<a class=\"bdt-slide-link\" href=\"#\">\n\n\t\t\t\t\t\t\t\t\tCONTACT US\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"bdt-slide-item swiper-slide bdt-slide-effect-left\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-slider-image-wrapper\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"962\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/entrepot-overlay-noir-1.png\" class=\"bdt-cover\" alt=\"Entreprise\" data-bdt-cover=\"1\" srcset=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/entrepot-overlay-noir-1.png 1600w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/entrepot-overlay-noir-1-300x180.png 300w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/entrepot-overlay-noir-1-1024x616.png 1024w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/entrepot-overlay-noir-1-768x462.png 768w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/entrepot-overlay-noir-1-1536x924.png 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-slide-desc bdt-position-large bdt-position-center bdt-position-z-index\">\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-slide-text\">\n\t\t\t\t\t\t\t\t<p><img decoding=\"async\" class=\"alignnone wp-image-2808\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/LOGO-GROUPE-LAVAGNA-SECURITE-FONDS-TRANSPARENT-ECRITURES-BLANCHES-1-300x211.png\" alt=\"\" width=\"400\" height=\"281\" srcset=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/LOGO-GROUPE-LAVAGNA-SECURITE-FONDS-TRANSPARENT-ECRITURES-BLANCHES-1-300x211.png 300w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/LOGO-GROUPE-LAVAGNA-SECURITE-FONDS-TRANSPARENT-ECRITURES-BLANCHES-1-1024x719.png 1024w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/LOGO-GROUPE-LAVAGNA-SECURITE-FONDS-TRANSPARENT-ECRITURES-BLANCHES-1-768x539.png 768w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/LOGO-GROUPE-LAVAGNA-SECURITE-FONDS-TRANSPARENT-ECRITURES-BLANCHES-1-1536x1078.png 1536w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/LOGO-GROUPE-LAVAGNA-SECURITE-FONDS-TRANSPARENT-ECRITURES-BLANCHES-1.png 1549w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/p><p style=\"padding-right: 95px;\">Depuis 2010, nous concevons des solutions de s\u00e9curit\u00e9 sur mesure dans le Golfe de Saint-Tropez, en alliant expertise locale et technologies de pointe pour vous offrir une protection toujours \u00e0 la hauteur de vos attentes.<\/p>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-slide-link-wrapper\">\n\t\t\t\t\t\t\t\t<a class=\"bdt-slide-link\" href=\"#\">\n\n\t\t\t\t\t\t\t\t\tCONTACT US\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"bdt-position-z-index bdt-position-center bdt-visible@m\">\n\t\t\t\t<div class=\"bdt-arrows-container bdt-slidenav-container\">\n\t\t\t\t\t<a href=\"\" class=\"bdt-navigation-prev bdt-slidenav-previous bdt-icon bdt-slidenav\">\n\t\t\t\t\t\t<i class=\"ep-icon-arrow-left-12\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<a href=\"\" class=\"bdt-navigation-next bdt-slidenav-next bdt-icon bdt-slidenav\">\n\t\t\t\t\t\t<i class=\"ep-icon-arrow-right-12\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e743ce5 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e743ce5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-545e36b\" data-id=\"545e36b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0a4363c elementor-widget elementor-widget-Elementor-About-widget\" data-id=\"0a4363c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"Elementor-About-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- about-area -->\n    <section id=\"about\" class=\"about-area about-p pt-90 pb-75 p-relative fix\">\n        <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col-lg-6 col-md-12 col-sm-12\">\n                    <div class=\"s-about-img p-relative\">\n                        <img decoding=\"async\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/08\/camera-securite-saint-tropez.png\" alt=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/08\/camera-securite-saint-tropez.png\">  \n                    <\/div>\n                <\/div>\n                \n                <div class=\"col-lg-6 col-md-12 col-sm-12\">\n                    <div class=\"about-content s-about-content\">\n                        <div class=\"about-title second-title pb-25\">  \n                            <h5><span class=\"line\"> <img decoding=\"async\" src=\"http:\/\/wordpress.zcube.in\/wesecure\/wp-content\/uploads\/2021\/07\/circle_right.png\" alt=\"http:\/\/wordpress.zcube.in\/wesecure\/wp-content\/uploads\/2021\/07\/circle_right.png\"><\/span><\/h5>\n                            <h2>Intelligent and personalized security solutions<\/h2>\n                        <\/div>\n                         <p>Our Mission: Secure goods and people, provide cutting-edge technologies and tailor-made strategies designed specifically to meet your unique needs.\n<\/p>                         <ul class=\"mt-30 mb-15\">\n                                   \n                                  <li>\n                                    <div class=\"icon\"><i class=\"fal fa-check\"><\/i><\/div>\n                                    <div class=\"text\">\n                                        <h4>Personalized study of your needs <\/h4>\n                                        <p>Driven by the pleasure of meeting each other, we will discover your property and your lifestyle. This approach allows us to design together a tailor-made solution that offers you perfect and personalized protection.\n<\/p>\n                                    <\/div>\n                                <\/li>\n                                <li>\n                                    <div class=\"icon\"><i class=\"fal fa-check\"><\/i><\/div>\n                                    <div class=\"text\">\n                                        <h4> Your comfort above all: security that adapts <\/h4>\n                                        <p>We offer adapted and effective protection, our solution must adapt to your needs. Each property is unique, each owner is unique. We offer simple use of complex systems. <\/p>\n                                    <\/div>\n                                <\/li>\n                               \n                            <\/ul> \n                        <div class=\"slider-btn\">                                          \n                            <a href=\"#contact\" class=\"btn ss-btn\">Get an appointment<\/a>\t\t\t\t\t\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/section>\n<!-- about-area-end -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c696de3 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"c696de3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8e8606f\" data-id=\"8e8606f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-472b1ef elementor-widget elementor-widget-heading\" data-id=\"472b1ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Solutions for individuals, professionals, <br>condominiums and communities <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b9d01d elementor-widget elementor-widget-heading\" data-id=\"4b9d01d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-medium\">For all types of risks<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f18cdf4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f18cdf4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fca2cb5\" data-id=\"fca2cb5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-029f297 elementor-widget elementor-widget-heading\" data-id=\"029f297\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Innovative family business<span style=\"font-family: Calibri;font-size: 62px;font-weight: 400\">.<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-752ecee\" data-id=\"752ecee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-091a3e9 elementor-widget elementor-widget-menu-anchor\" data-id=\"091a3e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"quisommesnous\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f29b8b elementor-widget elementor-widget-text-editor\" data-id=\"1f29b8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 2\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p>Created in 2010, the company GROUPE LAVAGNA S\u00c9CURIT\u00c9 is a family business with in-depth knowledge of the C\u00f4te d\u2019Azur, its activities, its geography and the related risks. Father and son work hand in hand in the design and implementation of personalized security services.<\/p><div class=\"page\" title=\"Page 2\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p>Parmi nos spe\u0301cificite\u0301s, celle d\u2019e\u0302tre inde\u0301pendants de toute gamme ou marque nous permet d\u2019enrichir tout au long de l\u2019anne\u0301e notre offre gra\u0302ce aux solutions les plus avance\u0301es du marche\u0301. Nous disposons ainsi d\u2019un choix technologique infini qui nous permet de re\u0301pondre de la fac\u0327on plus cible\u0301e a\u0300 notre cliente\u0300le.<\/p><\/div><\/div><div class=\"layoutArea\"><div class=\"column\"><p>We are trained by the greatest specialists around the world all year round.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1eb042f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1eb042f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b1b1db7\" data-id=\"b1b1db7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-49f1f8b elementor-widget elementor-widget-text-editor\" data-id=\"49f1f8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol class=\"ol1\">\n<li class=\"li1\"><span class=\"s2\">Passionn\u00e9s par les technologies de pointe, nous sommes des experts chevronn\u00e9s en analyse des risques et en protection des biens et des personnes. En tant qu\u2019int\u00e9grateurs s\u00e9curitaires, nous nous distinguons par notre capacit\u00e9 \u00e0 concevoir et \u00e0 mettre en place des syst\u00e8mes de s\u00e9curit\u00e9 innovants et efficaces. Notre mission principale est de d\u00e9velopper des solutions compl\u00e8tes de s\u00e9curit\u00e9, incluant des services avanc\u00e9s de t\u00e9l\u00e9surveillance agr\u00e9\u00e9 APSAD-P5. Gr\u00e2ce \u00e0 notre savoir-faire et \u00e0 notre engagement envers l&#8217;excellence, nous offrons une protection optimale adapt\u00e9e \u00e0 vos besoins sp\u00e9cifiques<\/span><\/li>\n<\/ol>\n<ol class=\"ol1\">\n<li>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>We act in complete confidentiality with total data protection. Leaders of the CAC 40, princely families, haute couture houses and many individuals trust us to secure their property and families.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/li>\n<li class=\"li1\"><span class=\"s2\">In an increasingly connected world, our expertise in cybersecurity and high technology ensures comfort and peace of mind, allowing you to navigate the digital age with confidence.<\/span><\/li>\n<\/ol>\n<ol class=\"ol1\">\n<li class=\"li1\"><span class=\"s2\">We ensure a continuous presence throughout the C\u00f4te d'Azur thanks to our technical on-call service available 24\/7, guaranteeing rapid and effective intervention in all circumstances.<\/span><\/li>\n<\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-11260f4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"11260f4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f869da2\" data-id=\"f869da2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b6d0b6 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0b6d0b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-05163c3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"05163c3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f7add2a\" data-id=\"f7add2a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70ac784 elementor-widget elementor-widget-heading\" data-id=\"70ac784\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Your Experts<span style=\"font-family: Calibri;font-size: 62px;font-weight: 400\">.<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-41fa690\" data-id=\"41fa690\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6785a97 elementor-widget elementor-widget-bdt-member\" data-id=\"6785a97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bdt-member.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"bdt-member skin-default bdt-transition-toggle\">\n\t\t\t\t\t\t\t<div class=\"bdt-member-photo-wrapper\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-member-photo\">\n\t\t\t\t\t\t<div class=\"\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"176\" height=\"223\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/eric-lavagna.jpg\" class=\"attachment-full size-full\" alt=\"Eric LAVAGNA\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"bdt-member-content\">\n\t\t\t\t\t\t\t\t\t<span class=\"bdt-member-name\">Eric LAVAGNA<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"bdt-member-role\">President<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-member-text bdt-content-wrap\">With more than 30 years of expertise in the security of goods and people, \u00c9ric LAVAGNA is unconditionally passionate about new things and challenges. A native of Saint-Tropez, his career began in large French groups, which made him want to found his own company with a much more personalized vision, where the range of possibilities would be accessible to him. \u00c9ric is passionate about sports and is keen to support many local sports associations.\n\u201cListening to my customers is my greatest strength.\u201d<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"bdt-member-icons\">\n\t\t\t\t\t\t\t<a class=\"bdt-member-icon elementor-repeater-item-f5f893a\" href=\"https:\/\/fr.linkedin.com\/company\/groupe-lavagna-securite-gls\" target=\"_blank\" data-bdt-tooltip=\"title: Linkedin;\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"fa-fw e-font-icon-svg e-fab-linkedin-in\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M100.28 448H7.4V148.9h92.88zM53.79 108.1C24.09 108.1 0 83.5 0 53.8a53.79 53.79 0 0 1 107.58 0c0 29.7-24.1 54.3-53.79 54.3zM447.9 448h-92.68V302.4c0-34.7-.7-79.2-48.29-79.2-48.29 0-55.69 37.7-55.69 76.7V448h-92.78V148.9h89.08v40.8h1.3c12.4-23.5 42.69-48.3 87.88-48.3 94 0 111.28 61.9 111.28 142.3V448z\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1acc95 elementor-widget elementor-widget-text-editor\" data-id=\"a1acc95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>E-mail:\u00a0 \u00a0 \u00a0<span style=\"color: #ffffff;\"><a style=\"color: #ffffff;\" href=\"\/en\/eric.lavagna@glssecurity.fr\/\">eric.lavagna@glssecurity.fr<\/a><\/span><\/p><p>Tel:\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 <span style=\"color: #ffffff;\"><a style=\"color: #ffffff;\" href=\"tel:0033760257218\">+33(0)7 60 25 72 18<\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a1d20fb\" data-id=\"a1d20fb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f8cb7d elementor-widget elementor-widget-bdt-member\" data-id=\"2f8cb7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bdt-member.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"bdt-member skin-default bdt-transition-toggle\">\n\t\t\t\t\t\t\t<div class=\"bdt-member-photo-wrapper\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"bdt-member-photo\">\n\t\t\t\t\t\t<div class=\"\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"175\" height=\"223\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/alexis-lavagna.jpg\" class=\"attachment-full size-full\" alt=\"Alexis LAVAGNA\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"bdt-member-content\">\n\t\t\t\t\t\t\t\t\t<span class=\"bdt-member-name\">Alexis LAVAGNA<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"bdt-member-role\">General Manager<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-member-text bdt-content-wrap\">Alexis LAVAGNA joined the family company as soon as she finished her studies. His passion for cutting-edge technologies brings the company a very innovative vision of security integration, particularly in the field of artificial intelligence. Alexis has a sense of relationships which gives him strong ties with customers. Born in Saint-Tropez, our region has no secrets for him.\n\u201cMy objective is to develop and perpetuate the reference status of GLS in our region for the well-being of our customers.\u201d\n\n<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"bdt-member-icons\">\n\t\t\t\t\t\t\t<a class=\"bdt-member-icon elementor-repeater-item-9f33e8a\" href=\"http:\/\/www.linkedin.com\/bdthemes\/\" target=\"_blank\" data-bdt-tooltip=\"title: Linkedin;\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"fa-fw e-font-icon-svg e-fab-linkedin-in\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M100.28 448H7.4V148.9h92.88zM53.79 108.1C24.09 108.1 0 83.5 0 53.8a53.79 53.79 0 0 1 107.58 0c0 29.7-24.1 54.3-53.79 54.3zM447.9 448h-92.68V302.4c0-34.7-.7-79.2-48.29-79.2-48.29 0-55.69 37.7-55.69 76.7V448h-92.78V148.9h89.08v40.8h1.3c12.4-23.5 42.69-48.3 87.88-48.3 94 0 111.28 61.9 111.28 142.3V448z\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81cd51d elementor-widget elementor-widget-text-editor\" data-id=\"81cd51d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>E-mail:\u00a0 \u00a0 <span style=\"color: #ffffff;\">\u00a0<a style=\"color: #ffffff;\" href=\"\/en\/alexis.lavagna@glssecurity.fr\/\">alexis.lavagna@glssecurity.fr<\/a><\/span><\/p><p>Tel:\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<span style=\"color: #ffffff;\"> <a style=\"color: #ffffff;\" href=\"tel:0033681701378\">+33(0)6 81 70 13 78<\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-89374cb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"89374cb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-68a9cc4\" data-id=\"68a9cc4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b0f9b51 elementor-widget elementor-widget-heading\" data-id=\"b0f9b51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">A structured process<span style=\"font-family: Calibri;font-size: 32px;font-weight: 400\">.<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1c820fe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c820fe\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a9fb5b3\" data-id=\"a9fb5b3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c06e06c elementor-widget elementor-widget-image\" data-id=\"c06e06c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"518\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/Chronologie-1.png\" class=\"attachment-2048x2048 size-2048x2048 wp-image-2868\" alt=\"\" srcset=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/Chronologie-1.png 1920w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/Chronologie-1-300x81.png 300w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/Chronologie-1-1024x276.png 1024w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/Chronologie-1-768x207.png 768w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/Chronologie-1-1536x414.png 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-a859217 e-con-full e-flex e-con e-parent\" data-id=\"a859217\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-52c8f3d e-con-full e-flex e-con e-child\" data-id=\"52c8f3d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ad3826c elementor-widget elementor-widget-image\" data-id=\"ad3826c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/06\/Visuel-maison-e1722434933460-1024x576.png\" class=\"attachment-large size-large wp-image-10\" alt=\"\" srcset=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/06\/Visuel-maison-e1722434933460-1024x576.png 1024w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/06\/Visuel-maison-e1722434933460-300x169.png 300w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/06\/Visuel-maison-e1722434933460-768x432.png 768w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/06\/Visuel-maison-e1722434933460.png 1091w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1341a39 e-con-full e-flex e-con e-child\" data-id=\"1341a39\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-82127b1 elementor-widget elementor-widget-image\" data-id=\"82127b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/residence-copropriete-1024x576.png\" class=\"attachment-large size-large wp-image-2822\" alt=\"Entreprise s\u00e9curit\u00e9 saint tropez\" srcset=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/residence-copropriete-1024x576.png 1024w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/residence-copropriete-300x169.png 300w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/residence-copropriete-768x432.png 768w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/residence-copropriete-1536x864.png 1536w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/residence-copropriete.png 1920w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7990c19 e-con-full e-flex e-con e-child\" data-id=\"7990c19\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-888ef15 elementor-widget elementor-widget-image\" data-id=\"888ef15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/entrepot-entreprise-1024x576.png\" class=\"attachment-large size-large wp-image-2823\" alt=\"Entreprise alarme sainte maxime\" srcset=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/entrepot-entreprise-1024x576.png 1024w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/entrepot-entreprise-300x169.png 300w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/entrepot-entreprise-768x432.png 768w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/entrepot-entreprise-1536x864.png 1536w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/entrepot-entreprise.png 1920w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-535a5db e-con-full e-flex e-con e-child\" data-id=\"535a5db\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-98443d3 elementor-widget elementor-widget-image\" data-id=\"98443d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"368\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2021\/01\/architecture-563614_1280-1024x589.jpg\" class=\"attachment-large size-large wp-image-2958\" alt=\"s\u00e9curit\u00e9 residence secondaire\" srcset=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2021\/01\/architecture-563614_1280-1024x589.jpg 1024w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2021\/01\/architecture-563614_1280-300x173.jpg 300w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2021\/01\/architecture-563614_1280-768x442.jpg 768w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2021\/01\/architecture-563614_1280.jpg 1280w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3d5e327 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3d5e327\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bd3e2ae\" data-id=\"bd3e2ae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-204ad7d elementor-widget elementor-widget-menu-anchor\" data-id=\"204ad7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"nosexpertises\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-008e55a elementor-widget elementor-widget-Elementor-service-one-widget\" data-id=\"008e55a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"Elementor-service-one-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<!-- services-three-area -->\r\n<section id=\"services-08\" class=\"services-08 pt-120 pb-120 p-relative fix\">\r\n    <div class=\"container\">\r\n        <div class=\"row services-08-item--wrapper mt-0\">\r\n            <div class=\"col-lg-4 col-md-4\">\r\n                <div class=\"section-title mb-50 text-left\">\r\n                    <h5><span class=\"line\"> <img decoding=\"async\" src=\"\" alt=\"\"><\/span><\/h5>\r\n                    <h2>\r\n                        Our expertise at your service<span style=\"color: rgb(231, 28, 36); font-family: Calibri; font-size: 62px; font-weight: 400; white-space-collapse: collapse;\">.<\/span>                    <\/h2>\r\n                <\/div>\r\n            <\/div>\r\n            \r\n                                <div class=\"col-lg-4 col-md-4 bdr\">\r\n                        <div class=\"services-08-item\">\r\n                            <div class=\"services-08-thumb\">\r\n                                <img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/ai.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"intelligence artificielle alarme saint tropez\" srcset=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/ai.png 512w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/ai-300x300.png 300w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/ai-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>                            <\/div>\r\n                            <div class=\"services-08-content\">\r\n                                <h3><a href=\"https:\/\/www.glssecurity.fr\/en\/service\/integration-intelligence-artificielle\/\"> Int\u00e9gration de l&#8217;intelligence artificielle<\/a><\/h3>\r\n                                \n<p>L&#8217;intelligence artificielle et l&#8217;automatisation de la cha\u00eene de s\u00e9curisation.<\/p>\n                                <a href=\"https:\/\/www.glssecurity.fr\/en\/service\/integration-intelligence-artificielle\/\" class=\"readmore\"><i class=\"fal fa-long-arrow-right\"><\/i><\/a>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                                <div class=\"col-lg-4 col-md-4 bdr\">\r\n                        <div class=\"services-08-item\">\r\n                            <div class=\"services-08-thumb\">\r\n                                <img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/la-reconnaissance-faciale.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"reconnaissance faciale saint tropez\" srcset=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/la-reconnaissance-faciale.png 512w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/la-reconnaissance-faciale-300x300.png 300w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/la-reconnaissance-faciale-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>                            <\/div>\r\n                            <div class=\"services-08-content\">\r\n                                <h3><a href=\"https:\/\/www.glssecurity.fr\/en\/service\/reconnaissance-facila\/\"> Facial recognition<\/a><\/h3>\r\n                                \n<p>The technology now recognizes members of your entourage or even authorized personnel.<\/p>\n                                <a href=\"https:\/\/www.glssecurity.fr\/en\/service\/reconnaissance-facila\/\" class=\"readmore\"><i class=\"fal fa-long-arrow-right\"><\/i><\/a>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n             \r\n                                <div class=\"col-lg-4 col-md-4 bdr\">\r\n                        <div class=\"services-08-item\">\r\n                            <div class=\"services-08-thumb\">\r\n                                <img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/intrusion.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"alarme anti intrusion saint tropez\" srcset=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/intrusion.png 512w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/intrusion-300x300.png 300w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/intrusion-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>                            <\/div>\r\n                            <div class=\"services-08-content\">\r\n                                <h3><a href=\"https:\/\/www.glssecurity.fr\/en\/service\/alarmes-anti-intrusion\/\"> Intruder alarms<\/a><\/h3>\r\n                                \n<p>Designed to detect unauthorized entry into your property.<\/p>\n                                <a href=\"https:\/\/www.glssecurity.fr\/en\/service\/alarmes-anti-intrusion\/\" class=\"readmore\"><i class=\"fal fa-long-arrow-right\"><\/i><\/a>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n             \r\n                                <div class=\"col-lg-4 col-md-4 bdr\">\r\n                        <div class=\"services-08-item\">\r\n                            <div class=\"services-08-thumb\">\r\n                                <img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/videosurveillance.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"videosurveillance ramatuelle\" srcset=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/videosurveillance.png 512w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/videosurveillance-300x300.png 300w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/videosurveillance-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>                            <\/div>\r\n                            <div class=\"services-08-content\">\r\n                                <h3><a href=\"https:\/\/www.glssecurity.fr\/en\/service\/video-surveillance\/\"> CCTV<\/a><\/h3>\r\n                                \n<p>A powerful tool that can be controlled remotely and in constant development<\/p>\n                                <a href=\"https:\/\/www.glssecurity.fr\/en\/service\/video-surveillance\/\" class=\"readmore\"><i class=\"fal fa-long-arrow-right\"><\/i><\/a>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n             \r\n                                <div class=\"col-lg-4 col-md-4 bdr\">\r\n                        <div class=\"services-08-item\">\r\n                            <div class=\"services-08-thumb\">\r\n                                <img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/thermique.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"analyse thermique saint tropez\" srcset=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/thermique.png 512w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/thermique-300x300.png 300w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/thermique-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>                            <\/div>\r\n                            <div class=\"services-08-content\">\r\n                                <h3><a href=\"https:\/\/www.glssecurity.fr\/en\/service\/detecteur-thermique\/\"> Analyse thermique<\/a><\/h3>\r\n                                \n<p>Instant analysis of any unexpected events within your property.<\/p>\n                                <a href=\"https:\/\/www.glssecurity.fr\/en\/service\/detecteur-thermique\/\" class=\"readmore\"><i class=\"fal fa-long-arrow-right\"><\/i><\/a>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n             \r\n                                <div class=\"col-lg-4 col-md-4 bdr\">\r\n                        <div class=\"services-08-item\">\r\n                            <div class=\"services-08-thumb\">\r\n                                <img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/drone-camera.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"anti drone saint tropez\" srcset=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/drone-camera.png 512w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/drone-camera-300x300.png 300w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/drone-camera-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>                            <\/div>\r\n                            <div class=\"services-08-content\">\r\n                                <h3><a href=\"https:\/\/www.glssecurity.fr\/en\/service\/lutte-anti-drone\/\"> Anti-drone fight<\/a><\/h3>\r\n                                \n<p>To guarantee aviation safety at very low altitude.<\/p>\n                                <a href=\"https:\/\/www.glssecurity.fr\/en\/service\/lutte-anti-drone\/\" class=\"readmore\"><i class=\"fal fa-long-arrow-right\"><\/i><\/a>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n             \r\n                                <div class=\"col-lg-4 col-md-4 bdr\">\r\n                        <div class=\"services-08-item\">\r\n                            <div class=\"services-08-thumb\">\r\n                                <img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/carre.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"specialiste perimetrie virtuelle saint tropez\" srcset=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/carre.png 512w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/carre-300x300.png 300w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/carre-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>                            <\/div>\r\n                            <div class=\"services-08-content\">\r\n                                <h3><a href=\"https:\/\/www.glssecurity.fr\/en\/service\/perimetrie-virtuelle\/\"> Virtual perimeter<\/a><\/h3>\r\n                                \n<p>Une barri\u00e8re de protection invisible autour de votre propri\u00e9t\u00e9 qui donne l&#8217;alerte en cas d&#8217;intrusion.<\/p>\n                                <a href=\"https:\/\/www.glssecurity.fr\/en\/service\/perimetrie-virtuelle\/\" class=\"readmore\"><i class=\"fal fa-long-arrow-right\"><\/i><\/a>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n             \r\n                                <div class=\"col-lg-4 col-md-4 bdr\">\r\n                        <div class=\"services-08-item\">\r\n                            <div class=\"services-08-thumb\">\r\n                                <img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/verrouillage-du-cloud.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"cybers\u00e9curit\u00e9 saint tropez\" srcset=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/verrouillage-du-cloud.png 512w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/verrouillage-du-cloud-300x300.png 300w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/verrouillage-du-cloud-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>                            <\/div>\r\n                            <div class=\"services-08-content\">\r\n                                <h3><a href=\"https:\/\/www.glssecurity.fr\/en\/service\/cybersecurite\/\"> Cybersecurity<\/a><\/h3>\r\n                                \n<p>Security of computer systems and data in compliance with RGDP regulations.<\/p>\n                                <a href=\"https:\/\/www.glssecurity.fr\/en\/service\/cybersecurite\/\" class=\"readmore\"><i class=\"fal fa-long-arrow-right\"><\/i><\/a>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n             \r\n                                <div class=\"col-lg-4 col-md-4 bdr\">\r\n                        <div class=\"services-08-item\">\r\n                            <div class=\"services-08-thumb\">\r\n                                <img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/analyse-biometrique.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"specialiste biometrie saint tropez\" srcset=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/analyse-biometrique.png 512w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/analyse-biometrique-300x300.png 300w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/analyse-biometrique-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>                            <\/div>\r\n                            <div class=\"services-08-content\">\r\n                                <h3><a href=\"https:\/\/www.glssecurity.fr\/en\/service\/biometrie\/\"> Biometrics<\/a><\/h3>\r\n                                \n<p>Recognition of individuals thanks to their physical characteristics.<\/p>\n                                <a href=\"https:\/\/www.glssecurity.fr\/en\/service\/biometrie\/\" class=\"readmore\"><i class=\"fal fa-long-arrow-right\"><\/i><\/a>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n             \r\n                                <div class=\"col-lg-4 col-md-4 bdr\">\r\n                        <div class=\"services-08-item\">\r\n                            <div class=\"services-08-thumb\">\r\n                                <img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/brumeux.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"generateur de brouillard saint tropez\" srcset=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/brumeux.png 512w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/brumeux-300x300.png 300w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/brumeux-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>                            <\/div>\r\n                            <div class=\"services-08-content\">\r\n                                <h3><a href=\"https:\/\/www.glssecurity.fr\/en\/service\/generateur-de-brouillard\/\"> Fog generator<\/a><\/h3>\r\n                                <p>Automated device destabilizing any intruder in your property.<\/p>\n                                <a href=\"https:\/\/www.glssecurity.fr\/en\/service\/generateur-de-brouillard\/\" class=\"readmore\"><i class=\"fal fa-long-arrow-right\"><\/i><\/a>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n             \r\n                                <div class=\"col-lg-4 col-md-4 bdr\">\r\n                        <div class=\"services-08-item\">\r\n                            <div class=\"services-08-thumb\">\r\n                                <img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/reseau-mondial.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"s\u00e9curit\u00e9 r\u00e9seau saint tropez\" srcset=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/reseau-mondial.png 512w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/reseau-mondial-300x300.png 300w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/reseau-mondial-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>                            <\/div>\r\n                            <div class=\"services-08-content\">\r\n                                <h3><a href=\"https:\/\/www.glssecurity.fr\/en\/service\/reseau\/\"> R\u00e9seau Internet<\/a><\/h3>\r\n                                <p>Installation structur\u00e9e d&#8217;un r\u00e9seau internet garantissant la meilleure interactivit\u00e9 de vos appareils.<\/p>\n                                <a href=\"https:\/\/www.glssecurity.fr\/en\/service\/reseau\/\" class=\"readmore\"><i class=\"fal fa-long-arrow-right\"><\/i><\/a>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n             \r\n                                <div class=\"col-lg-4 col-md-4 bdr\">\r\n                        <div class=\"services-08-item\">\r\n                            <div class=\"services-08-thumb\">\r\n                                <img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/visiophone.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"visiophone-saint-tropez\" srcset=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/visiophone.png 512w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/visiophone-300x300.png 300w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/visiophone-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>                            <\/div>\r\n                            <div class=\"services-08-content\">\r\n                                <h3><a href=\"https:\/\/www.glssecurity.fr\/en\/service\/video-portier\/\"> DCM outdoor video station<\/a><\/h3>\r\n                                <p>Appel vid\u00e9o avec enregistrement situ\u00e9 \u00e0 l&#8217;entr\u00e9e de votre propri\u00e9t\u00e9.<\/p>\n                                <a href=\"https:\/\/www.glssecurity.fr\/en\/service\/video-portier\/\" class=\"readmore\"><i class=\"fal fa-long-arrow-right\"><\/i><\/a>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n             \r\n                                <div class=\"col-lg-4 col-md-4 bdr\">\r\n                        <div class=\"services-08-item\">\r\n                            <div class=\"services-08-thumb\">\r\n                                <img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/domotique.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"entreprise domotique saint tropez\" srcset=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/domotique.png 512w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/domotique-300x300.png 300w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/domotique-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>                            <\/div>\r\n                            <div class=\"services-08-content\">\r\n                                <h3><a href=\"https:\/\/www.glssecurity.fr\/en\/service\/domotique\/\"> Home automation<\/a><\/h3>\r\n                                <p>Automated management techniques applied to your property<\/p>\n                                <a href=\"https:\/\/www.glssecurity.fr\/en\/service\/domotique\/\" class=\"readmore\"><i class=\"fal fa-long-arrow-right\"><\/i><\/a>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                    \r\n        <\/div>\r\n    <\/div>\r\n<\/section>\r\n<!-- services-three-area -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fdfbd76 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"fdfbd76\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a5f7b2d\" data-id=\"a5f7b2d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-711230f elementor-widget elementor-widget-Elementor-counter-widget\" data-id=\"711230f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"Elementor-counter-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<!-- counter-area -->\r\n    <div class=\"counter-area p-relative pt-50 pb-50\" style=\"background-image:url(https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/counter-black.png)\">\r\n        <div class=\"container\">\r\n            <div class=\"row p-relative\">\r\n                                                            <div class=\"col-lg-3 col-md-6 col-sm-6\">\r\n                            <div class=\"single-counter\">\r\n                                <div class=\"counter p-relative\">\r\n                                    <span class=\"count\">14<\/span><small>+<\/small>                                    \r\n                                    <p>Years of experience<\/p>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                                        <div class=\"col-lg-3 col-md-6 col-sm-6\">\r\n                            <div class=\"single-counter\">\r\n                                <div class=\"counter p-relative\">\r\n                                    <span class=\"count\">2840<\/span><small>+<\/small>                                    \r\n                                    <p>Completed Projects<\/p>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                                        <div class=\"col-lg-3 col-md-6 col-sm-6\">\r\n                            <div class=\"single-counter\">\r\n                                <div class=\"counter p-relative\">\r\n                                    <span class=\"count\">5837<\/span><small>+<\/small>                                    \r\n                                    <p>Coffee cups<\/p>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                                        <div class=\"col-lg-3 col-md-6 col-sm-6\">\r\n                            <div class=\"single-counter\">\r\n                                <div class=\"counter p-relative\">\r\n                                    <span class=\"count\">365<\/span><small>+<\/small>                                    \r\n                                    <p>Action days per year<\/p>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                 \r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<!-- counter-area-end -->\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-66cc112 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"66cc112\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3a5498d\" data-id=\"3a5498d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9360579 elementor-widget elementor-widget-spacer\" data-id=\"9360579\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9650219 elementor-widget elementor-widget-menu-anchor\" data-id=\"9650219\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"nosclients\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b382e3 elementor-widget elementor-widget-heading\" data-id=\"0b382e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">They trust us<span style=\"font-family: Calibri;font-size: 32px;font-weight: 400\">.<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-772dc6d elementor-widget elementor-widget-spacer\" data-id=\"772dc6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88308bb elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"88308bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;7&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d\u2019images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/cl-Emilio-Pucci-logo.png\" alt=\"cl Emilio-Pucci-logo\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/cl-monaco-marine-150x150.png\" alt=\"cl monaco marine\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 sur 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/cl-opera-150x150.png\" alt=\"cl opera\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 sur 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/cl-saint-tropez-150x150.png\" alt=\"cl saint tropez\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 sur 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/cl-DIOR-150x150.png\" alt=\"cl DIOR\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 sur 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/cl-bertaud-belieu.png\" alt=\"cl bertaud belieu\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 sur 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/cl-naval-groupe-150x150.png\" alt=\"cl naval groupe\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-13c736a elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"13c736a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-61d428c\" data-id=\"61d428c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b65d538 elementor-widget elementor-widget-heading\" data-id=\"b65d538\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Our mission, if you accept it: to provide you with first-rate security through advanced technological solutions and excellent service.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-305a244 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"305a244\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d34d5b6\" data-id=\"d34d5b6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a486fb elementor-widget elementor-widget-menu-anchor\" data-id=\"7a486fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"nosconseils\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7b1962 elementor-widget elementor-widget-Elementor-Widget-Blog\" data-id=\"c7b1962\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"Elementor-Widget-Blog.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\r\n<!-- blog-area -->\r\n    <section id=\"blog\" class=\"blog-area  p-relative pt-120 pb-90 fix\">\r\n        <div class=\"container\">\r\n            <div class=\"row align-items-center\"> \r\n                <div class=\"col-lg-12\">\r\n                    <div class=\"section-title center-align mb-50 text-center\">\r\n                        <h5><span class=\"line2\"> <img decoding=\"async\" src=\"\" alt=\"\"><\/span><\/h5>\r\n                        <h2>\r\n                            Our advice                        <\/h2>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n            \r\n            <div class=\"row\">\r\n                                \r\n<div class=\"col-lg-4 col-md-12\">\r\n    <div class=\"single-post2 mb-30\">\r\n        <div class=\"blog-thumb2\">\r\n            <a href=\"https:\/\/www.glssecurity.fr\/en\/2025\/11\/05\/alarme-de-securite-pour-maison-protegez-votre-foyer-efficacement\/\"><\/a>\r\n        <\/div>                    \r\n        <div class=\"blog-content2\">     \r\n            <div class=\"date-home\">\r\n            <i class=\"fal fa-calendar-alt\"><\/i>             <\/div>\r\n            <h4><a href=\"https:\/\/www.glssecurity.fr\/en\/2025\/11\/05\/alarme-de-securite-pour-maison-protegez-votre-foyer-efficacement\/\">Alarme de s\u00e9curit\u00e9 pour maison : Prot\u00e9gez votre foyer efficacement<\/a><\/h4>      \r\n            <p>S\u00e9curit\u00e9 priv\u00e9e \u00e0 Gassin : Guide complet 2025 Introduction La s\u00e9curit\u00e9 pri<\/p>\r\n            <div class=\"blog-btn\"><a href=\"https:\/\/www.glssecurity.fr\/en\/2025\/11\/05\/alarme-de-securite-pour-maison-protegez-votre-foyer-efficacement\/\">Read More<\/a><\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n<div class=\"col-lg-4 col-md-12\">\r\n    <div class=\"single-post2 mb-30\">\r\n        <div class=\"blog-thumb2\">\r\n            <a href=\"https:\/\/www.glssecurity.fr\/en\/2024\/07\/17\/dix-conseils-pour-securitser-votre-maison-a-saint-tropez\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"752\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/SAINT-TROPEZ-1170x752.jpg\" class=\"attachment-wesecure-featured-large size-wesecure-featured-large wp-post-image\" alt=\"Port de Saint-Tropez\" srcset=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/SAINT-TROPEZ-1170x752.jpg 1170w, https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/SAINT-TROPEZ-370x238.jpg 370w\" sizes=\"(max-width: 1170px) 100vw, 1170px\" \/><\/a>\r\n        <\/div>                    \r\n        <div class=\"blog-content2\">     \r\n            <div class=\"date-home\">\r\n            <i class=\"fal fa-calendar-alt\"><\/i>             <\/div>\r\n            <h4><a href=\"https:\/\/www.glssecurity.fr\/en\/2024\/07\/17\/dix-conseils-pour-securitser-votre-maison-a-saint-tropez\/\">10 essential tips for securing your home in Saint-Tropez<\/a><\/h4>      \r\n            <p>Vid\u00e9osurveillance Haut de Gamme \u00e0 Saint-Tropez : S\u00e9curisez Votre Maison de Lu<\/p>\r\n            <div class=\"blog-btn\"><a href=\"https:\/\/www.glssecurity.fr\/en\/2024\/07\/17\/dix-conseils-pour-securitser-votre-maison-a-saint-tropez\/\">Read More<\/a><\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n<div class=\"col-lg-4 col-md-12\">\r\n    <div class=\"single-post2 mb-30\">\r\n        <div class=\"blog-thumb2\">\r\n            <a href=\"https:\/\/www.glssecurity.fr\/en\/2024\/06\/25\/securiser-votre-maison-de-vacances-astuces-et-recommandations\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"736\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2021\/01\/architecture-563614_1280-1170x736.jpg\" class=\"attachment-wesecure-featured-large size-wesecure-featured-large wp-post-image\" alt=\"s\u00e9curit\u00e9 residence secondaire\" \/><\/a>\r\n        <\/div>                    \r\n        <div class=\"blog-content2\">     \r\n            <div class=\"date-home\">\r\n            <i class=\"fal fa-calendar-alt\"><\/i>             <\/div>\r\n            <h4><a href=\"https:\/\/www.glssecurity.fr\/en\/2024\/06\/25\/securiser-votre-maison-de-vacances-astuces-et-recommandations\/\">Securing your vacation home: tips and recommendations<\/a><\/h4>      \r\n            <p>\ud83c\udfd6\ufe0f S\u00e9curit\u00e9 Maison de Vacances \u00e0 Saint-Tropez : Prot\u00e9gez Votre Bien ave<\/p>\r\n            <div class=\"blog-btn\"><a href=\"https:\/\/www.glssecurity.fr\/en\/2024\/06\/25\/securiser-votre-maison-de-vacances-astuces-et-recommandations\/\">Read More<\/a><\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>                                            <\/div>\r\n        <\/div>\r\n    <\/section>\r\n<!-- blog-area-end -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87490c3 elementor-widget elementor-widget-menu-anchor\" data-id=\"87490c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"contact\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-32211eb elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"32211eb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2e89624\" data-id=\"2e89624\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d3bc179 elementor-widget elementor-widget-heading\" data-id=\"d3bc179\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contact<span style=\"font-family: Calibri;font-size: 62px;font-weight: 400\">.<\/span>\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-52ff7e7 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"52ff7e7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bd428d9\" data-id=\"bd428d9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b49e3a elementor-widget elementor-widget-google_maps\" data-id=\"3b49e3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=GROUPE%20LAVAGNA&#038;t=m&#038;z=14&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"GROUPE LAVAGNA\"\n\t\t\t\t\taria-label=\"GROUPE LAVAGNA\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-13e8e75 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"13e8e75\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1f0bd7b\" data-id=\"1f0bd7b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18150a7 elementor-widget elementor-widget-image\" data-id=\"18150a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/08\/LOGO-GROUPE-LAVAGNA-SECURITE-LETTERS-BLANC.png\" title=\"GLS SAINT TROPEZ\" alt=\"GLS SAINT TROPEZ\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0b0cfd elementor-widget elementor-widget-Elementor-brand-widget\" data-id=\"e0b0cfd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"Elementor-brand-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n\r\n<!-- contact-area -->\r\n<section id=\"contacts\" class=\"contact-area after-none contact-bg p-relative fix pt-90 pb-30\" style=\"background-image:url(https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/fond-noir.png)\" >\r\n    <div class=\"container\">\r\n        <div class=\"row\">\r\n            <div class=\"col-lg-12\">\r\n                <div class=\"contact-info\">\r\n                                                                        <div class=\"single-cta pb-30 mb-30 wow fadeInUp animated\" data-animation=\"fadeInDown animated\" data-delay=\".2s\">\r\n                                <div class=\"f-cta-icon\">\r\n                                    <i class=\"far fa-map\"><\/i>\r\n                                <\/div>\r\n                                    <h5>Agency<\/h5>\r\n                                 <p>1100 RD 98 <br> Les Cyclades <br>\n                                    83580 GASSIN, France<\/p>                            <\/div>\r\n                                                <div class=\"single-cta pb-30 mb-30 wow fadeInUp animated\" data-animation=\"fadeInDown animated\" data-delay=\".2s\">\r\n                                <div class=\"f-cta-icon\">\r\n                                    <i class=\"far fa-bell\"><\/i>\r\n                                <\/div>\r\n                                    <h5>Telephone<\/h5>\r\n                                 <p>+33 (0)4 94 96 93 42<br> \n                                    <\/p>                            <\/div>\r\n                                                <div class=\"single-cta pb-30 mb-30 wow fadeInUp animated\" data-animation=\"fadeInDown animated\" data-delay=\".2s\">\r\n                                <div class=\"f-cta-icon\">\r\n                                    <i class=\"far fa-envelope-open\"><\/i>\r\n                                <\/div>\r\n                                    <h5>E-mail<\/h5>\r\n                                  <p> <a href=\"#\">contact@glssecurity.fr<\/a><br><a                             <\/div>\r\n                     \r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/section>\r\n<!-- contact-area-end -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0ee58bb elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"0ee58bb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-59d4d0b\" data-id=\"59d4d0b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-490a303 elementor-widget elementor-widget-Elementor_contacts-widget\" data-id=\"490a303\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"Elementor_contacts-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- contact-area -->\n    <section id=\"contact\" class=\"contact-area after-none contact-bg pt-120 pb-120 p-relative fix\">\n        <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col-lg-12 order-2\">\n                    <div class=\"contact-bg02\">\n                        <div class=\"section-title center-align text-center\">\n                            <h2>\n                                Get an appointment                            <\/h2>\n                        <\/div>\n                        <div class=\"contact-form mt-30\">\n                            \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f2786-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"2786\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/2641#wpcf7-f2786-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/en\/wp-json\/wp\/v2\/pages\/2641#wpcf7-f2786-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"2786\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f2786-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"row\">\n\t<div class=\"col-lg-6\">\n\t\t<div class=\"contact-field p-relative c-name mb-30\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"fname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"First name\" value=\"\" type=\"text\" name=\"fname\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"col-lg-6\">\n\t\t<div class=\"contact-field p-relative c-email mb-20\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"lname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Surname\" value=\"\" type=\"text\" name=\"lname\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"col-lg-6\">\n\t\t<div class=\"contact-field p-relative c-subject mb-30\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-mail\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"col-lg-6\">\n\t\t<div class=\"contact-field p-relative c-subject mb-30\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"tel\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Telephone\" value=\"\" type=\"tel\" name=\"tel\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"col-lg-12\">\n\t\t<div class=\"contact-field p-relative c-subject mb-30\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Subject\" value=\"\" type=\"text\" name=\"subject\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"col-lg-12\">\n\t\t<div class=\"contact-field p-relative c-message mb-30\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Message\" name=\"message\"><\/textarea><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"quiz-587\"><label><span class=\"wpcf7-quiz-label\">What is the capital of France?<\/span> <input size=\"40\" class=\"wpcf7-form-control wpcf7-quiz Quiz\" id=\"Quiz\" autocomplete=\"off\" aria-required=\"true\" aria-invalid=\"false\" type=\"text\" name=\"quiz-587\" \/><\/label><input type=\"hidden\" name=\"_wpcf7_quiz_answer_quiz-587\" value=\"629dbe9eee50bf41d475f42d29bee2f5\" \/><\/span>\n\t\t<\/p>\n\t\t<div class=\"slider-btn text-center\">\n\t\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner btn ss-btn active\" type=\"submit\" value=\"Send\" \/>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form>\n<\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/section>\n<!-- contact-area-end -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-bc85c59 e-flex e-con-boxed e-con e-parent\" data-id=\"bc85c59\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ba7981d e-con-full e-flex e-con e-child\" data-id=\"ba7981d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8a3c46a e-con-full e-flex e-con e-child\" data-id=\"8a3c46a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-89728e6 elementor-widget elementor-widget-text-editor\" data-id=\"89728e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: right;\"><span style=\"color: #000000;\">or\u2026 stop by for a coffee!\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0edeed1 e-con-full e-flex e-con e-child\" data-id=\"0edeed1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-61efea0 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"61efea0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-coffee\" viewbox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M192 384h192c53 0 96-43 96-96h32c70.6 0 128-57.4 128-128S582.6 32 512 32H120c-13.3 0-24 10.7-24 24v232c0 53 43 96 96 96zM512 96c35.3 0 64 28.7 64 64s-28.7 64-64 64h-32V96h32zm47.7 384H48.3c-47.6 0-61-64-36-64h583.3c25 0 11.8 64-35.9 64z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Depuis 2010, nous concevons des solutions de s\u00e9curit\u00e9 sur mesure dans le Golfe de Saint-Tropez, en alliant expertise locale et technologies de pointe pour vous offrir une protection toujours \u00e0 la hauteur de vos attentes. NOUS CONTACTER Depuis 2010, nous concevons des solutions de s\u00e9curit\u00e9 sur mesure dans le Golfe de Saint-Tropez, en alliant expertise [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"home-page-one.php","meta":{"footnotes":""},"class_list":["post-2641","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alarme vid\u00e9osurveillance golfe de Saint-Tropez - Groupe Lavagna S\u00e9curit\u00e9<\/title>\n<meta name=\"description\" content=\"Experts en installation d&#039;alarmes et solutions de s\u00e9curit\u00e9 sur mesure \u00e0 Saint-Tropez. Protection des biens et personnes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.glssecurity.fr\/en\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alarme vid\u00e9osurveillance golfe de Saint-Tropez - Groupe Lavagna S\u00e9curit\u00e9\" \/>\n<meta property=\"og:description\" content=\"Experts en installation d&#039;alarmes et solutions de s\u00e9curit\u00e9 sur mesure \u00e0 Saint-Tropez. Protection des biens et personnes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.glssecurity.fr\/en\/\" \/>\n<meta property=\"og:site_name\" content=\"Groupe Lavagna S\u00e9curit\u00e9\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-06T14:49:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/villa-saint-tropez-overlay-noir-1.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.glssecurity.fr\\\/\",\"url\":\"https:\\\/\\\/www.glssecurity.fr\\\/\",\"name\":\"Alarme vid\u00e9osurveillance golfe de Saint-Tropez - Groupe Lavagna S\u00e9curit\u00e9\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.glssecurity.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.glssecurity.fr\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.glssecurity.fr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.glssecurity.fr\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/villa-saint-tropez-overlay-noir-1.png\",\"datePublished\":\"2021-07-31T06:19:39+00:00\",\"dateModified\":\"2025-11-06T14:49:14+00:00\",\"description\":\"Experts en installation d'alarmes et solutions de s\u00e9curit\u00e9 sur mesure \u00e0 Saint-Tropez. Protection des biens et personnes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.glssecurity.fr\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.glssecurity.fr\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.glssecurity.fr\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.glssecurity.fr\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/villa-saint-tropez-overlay-noir-1.png\",\"contentUrl\":\"https:\\\/\\\/www.glssecurity.fr\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/villa-saint-tropez-overlay-noir-1.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.glssecurity.fr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.glssecurity.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alarme vid\u00e9osurveillance golfe de Saint-Tropez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.glssecurity.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.glssecurity.fr\\\/\",\"name\":\"Groupe Lavagna S\u00e9curit\u00e9\",\"description\":\"Un nouveau regard sur votre s\u00e9curit\u00e9\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.glssecurity.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.glssecurity.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.glssecurity.fr\\\/#organization\",\"name\":\"Groupe Lavagna S\u00e9curit\u00e9\",\"url\":\"https:\\\/\\\/www.glssecurity.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.glssecurity.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.glssecurity.fr\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-LOGO-GROUPE-LAVAGNA-SECURITE-carre-250x.png\",\"contentUrl\":\"https:\\\/\\\/www.glssecurity.fr\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-LOGO-GROUPE-LAVAGNA-SECURITE-carre-250x.png\",\"width\":250,\"height\":250,\"caption\":\"Groupe Lavagna S\u00e9curit\u00e9\"},\"image\":{\"@id\":\"https:\\\/\\\/www.glssecurity.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alarme vid\u00e9osurveillance golfe de Saint-Tropez - Groupe Lavagna S\u00e9curit\u00e9","description":"Experts en installation d'alarmes et solutions de s\u00e9curit\u00e9 sur mesure \u00e0 Saint-Tropez. Protection des biens et personnes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.glssecurity.fr\/en\/","og_locale":"en_GB","og_type":"article","og_title":"Alarme vid\u00e9osurveillance golfe de Saint-Tropez - Groupe Lavagna S\u00e9curit\u00e9","og_description":"Experts en installation d'alarmes et solutions de s\u00e9curit\u00e9 sur mesure \u00e0 Saint-Tropez. Protection des biens et personnes.","og_url":"https:\/\/www.glssecurity.fr\/en\/","og_site_name":"Groupe Lavagna S\u00e9curit\u00e9","article_modified_time":"2025-11-06T14:49:14+00:00","og_image":[{"url":"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/villa-saint-tropez-overlay-noir-1.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.glssecurity.fr\/","url":"https:\/\/www.glssecurity.fr\/","name":"Alarme vid\u00e9osurveillance golfe de Saint-Tropez - Groupe Lavagna S\u00e9curit\u00e9","isPartOf":{"@id":"https:\/\/www.glssecurity.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.glssecurity.fr\/#primaryimage"},"image":{"@id":"https:\/\/www.glssecurity.fr\/#primaryimage"},"thumbnailUrl":"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/villa-saint-tropez-overlay-noir-1.png","datePublished":"2021-07-31T06:19:39+00:00","dateModified":"2025-11-06T14:49:14+00:00","description":"Experts en installation d'alarmes et solutions de s\u00e9curit\u00e9 sur mesure \u00e0 Saint-Tropez. Protection des biens et personnes.","breadcrumb":{"@id":"https:\/\/www.glssecurity.fr\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.glssecurity.fr\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.glssecurity.fr\/#primaryimage","url":"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/villa-saint-tropez-overlay-noir-1.png","contentUrl":"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/villa-saint-tropez-overlay-noir-1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.glssecurity.fr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.glssecurity.fr\/"},{"@type":"ListItem","position":2,"name":"Alarme vid\u00e9osurveillance golfe de Saint-Tropez"}]},{"@type":"WebSite","@id":"https:\/\/www.glssecurity.fr\/#website","url":"https:\/\/www.glssecurity.fr\/","name":"Groupe Lavagna S\u00e9curit\u00e9","description":"A new look at your security","publisher":{"@id":"https:\/\/www.glssecurity.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.glssecurity.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.glssecurity.fr\/#organization","name":"Groupe Lavagna S\u00e9curit\u00e9","url":"https:\/\/www.glssecurity.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.glssecurity.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/cropped-LOGO-GROUPE-LAVAGNA-SECURITE-carre-250x.png","contentUrl":"https:\/\/www.glssecurity.fr\/wp-content\/uploads\/2024\/07\/cropped-LOGO-GROUPE-LAVAGNA-SECURITE-carre-250x.png","width":250,"height":250,"caption":"Groupe Lavagna S\u00e9curit\u00e9"},"image":{"@id":"https:\/\/www.glssecurity.fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.glssecurity.fr\/en\/wp-json\/wp\/v2\/pages\/2641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.glssecurity.fr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.glssecurity.fr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.glssecurity.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.glssecurity.fr\/en\/wp-json\/wp\/v2\/comments?post=2641"}],"version-history":[{"count":343,"href":"https:\/\/www.glssecurity.fr\/en\/wp-json\/wp\/v2\/pages\/2641\/revisions"}],"predecessor-version":[{"id":3245,"href":"https:\/\/www.glssecurity.fr\/en\/wp-json\/wp\/v2\/pages\/2641\/revisions\/3245"}],"wp:attachment":[{"href":"https:\/\/www.glssecurity.fr\/en\/wp-json\/wp\/v2\/media?parent=2641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}